{"id":544,"date":"2025-09-08T11:04:41","date_gmt":"2025-09-08T14:04:41","guid":{"rendered":"https:\/\/sites.uel.br\/teatroouroverde\/?p=544"},"modified":"2025-09-18T11:31:22","modified_gmt":"2025-09-18T14:31:22","slug":"bastidores-de-um-circo-ainda-mais-diferente","status":"publish","type":"post","link":"https:\/\/sites.uel.br\/teatroouroverde\/programacao\/2025\/09\/08\/bastidores-de-um-circo-ainda-mais-diferente\/","title":{"rendered":"Bastidores de um circo ainda mais diferente promete encantar londrinenses"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sites.uel.br\/teatroouroverde\/wp-content\/uploads\/2025\/09\/circo-diferente-fotos-vitor-pedrassoni-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-624\" style=\"width:664px;height:auto\" srcset=\"https:\/\/sites.uel.br\/teatroouroverde\/wp-content\/uploads\/2025\/09\/circo-diferente-fotos-vitor-pedrassoni-1-1024x682.jpeg 1024w, https:\/\/sites.uel.br\/teatroouroverde\/wp-content\/uploads\/2025\/09\/circo-diferente-fotos-vitor-pedrassoni-1-300x200.jpeg 300w, https:\/\/sites.uel.br\/teatroouroverde\/wp-content\/uploads\/2025\/09\/circo-diferente-fotos-vitor-pedrassoni-1-768x512.jpeg 768w, https:\/\/sites.uel.br\/teatroouroverde\/wp-content\/uploads\/2025\/09\/circo-diferente-fotos-vitor-pedrassoni-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Voc\u00ea est\u00e1 convidado a mergulhar na magia do espet\u00e1culo musical \u201cOs Bastidores de Um Circo Ainda Mais Diferente\u201d. A apresenta\u00e7\u00e3o, agendada para o dia 20 de setembro, \u00e0s 17h, no Teatro Ouro Verde, n\u00e3o \u00e9 apenas uma celebra\u00e7\u00e3o da arte, mas uma a\u00e7\u00e3o solid\u00e1ria em apoio ao projeto M\u00fasica Crian\u00e7a.<\/p>\n\n\n\n<p>O espet\u00e1culo \u00e9 uma jornada musical que explora o universo de um circo \u00fanico, combinando m\u00fasica e teatro com uma narrativa envolvente. O espet\u00e1culo \u00e9 uma celebra\u00e7\u00e3o da criatividade e da inclus\u00e3o. A montagem leva ao palco do Ouro Verde, m\u00fasica tocada por aproximadamente 50 instrumentistas de todas as idades do Est\u00fadio Flauta e Fole, do Projeto M\u00fasica Crian\u00e7a e da Escola de M\u00fasica Batuque.<\/p>\n\n\n\n<p>Os ingressos ainda podem ser adquiridos na bilheteria do Teatro Ouro Verde ou no Est\u00fadio Flauta e Fole pelo valor de R$50,00 (inteira) e R$25,00 (meia entrada).<\/p>\n\n\n\n<p><strong>Ingresso solid\u00e1rio<\/strong><\/p>\n\n\n\n<p>Al\u00e9m de contribuir para a manuten\u00e7\u00e3o do Projeto M\u00fasica Crian\u00e7a, esse espet\u00e1culo conta ainda com mais um desafio: arrecadar 150 ingressos solid\u00e1rios para que crian\u00e7as, jovens e fam\u00edlias do Instituto dos Cegos de Londrina, o ILECE e a Ciranda Cultural possam viver a experi\u00eancia de assistir a uma apresenta\u00e7\u00e3o musical no teatro.<\/p>\n\n\n\n<p>Cada ingresso doado, no valor de R$ 25,00, se transforma em uma oportunidade de inclus\u00e3o. &#8220;Queremos que este momento de arte e inclus\u00e3o chegue a todos. Acreditamos que a cultura \u00e9 um direito e que eventos como este podem transformar vidas. Convidamos as pessoas a comprarem um convite para si e um para destinarem a campanha de ingresso solid\u00e1rio&#8221;, afirmam Luciana Schmidt e Miguel Santos, produtores e diretores do espet\u00e1culo.<\/p>\n\n\n\n<p>Os ingressos solid\u00e1rios est\u00e3o sendo comercializados no valor \u00fanico de R$25,00. Para doar, basta fazer um PIX para a chave 43 984269683 (celular).<\/p>\n\n\n\n<p><strong>Projeto M\u00fasica Crian\u00e7a<\/strong><\/p>\n\n\n\n<p>O Projeto M\u00fasica Crian\u00e7a \u00e9 uma iniciativa de extens\u00e3o da Universidade Estadual de Londrina (UEL) que existe h\u00e1 quase 20 anos. O principal objetivo \u00e9 produzir e levar m\u00fasica de qualidade para o p\u00fablico infantil. Uma das miss\u00f5es mais importantes do projeto \u00e9 promover a inclus\u00e3o cultural. Eles realizam apresenta\u00e7\u00f5es e oficinas em escolas p\u00fablicas e buscam garantir que crian\u00e7as de institui\u00e7\u00f5es sociais possam ter acesso \u00e0 cultura. O projeto tamb\u00e9m serve como um campo de aprendizado para os alunos de gradua\u00e7\u00e3o da UEL, especialmente do curso de M\u00fasica. Eles participam de todo o processo de cria\u00e7\u00e3o e produ\u00e7\u00e3o, desde a composi\u00e7\u00e3o at\u00e9 a apresenta\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><em>Servi\u00e7o:<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>&#8220;Os Bastidores de Um Circo Ainda Mais Diferente&#8221;<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>20\/09\/2025 \u2013 17h \u2013 Teatro Ouro Verde<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Ingressos e informa\u00e7\u00f5es: Luciana Schmidt, pelo telefone 43 98426-9683<\/em><\/strong><\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es consulte o Instagram: <a href=\"https:\/\/www.instagram.com\/flautaefole\/\">https:\/\/www.instagram.com\/flautaefole\/<\/a><\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Texto: Emilia Miyazaki &#8211;\u00a0Jornalista<\/strong><\/h6>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea est\u00e1 convidado a mergulhar na magia do espet\u00e1culo musical \u201cOs Bastidores de Um Circo Ainda Mais Diferente\u201d. A apresenta\u00e7\u00e3o, agendada para o dia 20 de setembro, \u00e0s 17h, no Teatro Ouro Verde, n\u00e3o \u00e9 apenas uma celebra\u00e7\u00e3o da arte, mas uma a\u00e7\u00e3o solid\u00e1ria em apoio ao projeto M\u00fasica Crian\u00e7a. O espet\u00e1culo \u00e9 uma jornada [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programacao"],"acf":[],"_links":{"self":[{"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/posts\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":7,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"predecessor-version":[{"id":628,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/posts\/544\/revisions\/628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/media\/546"}],"wp:attachment":[{"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.uel.br\/teatroouroverde\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}