{"id":35068,"date":"2025-08-01T15:32:31","date_gmt":"2025-08-01T18:32:31","guid":{"rendered":"https:\/\/sites.uel.br\/prograd\/?page_id=35068"},"modified":"2025-08-04T16:12:09","modified_gmt":"2025-08-04T19:12:09","slug":"decretos-renovacao-de-cursos-quimica-bacharelado","status":"publish","type":"page","link":"https:\/\/sites.uel.br\/prograd\/decretos-renovacao-de-cursos-quimica-bacharelado\/","title":{"rendered":"Decretos (Renova\u00e7\u00e3o de Cursos)"},"content":{"rendered":"\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00edmica &#8211; Bacharelado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reconhecimento:<\/strong> Decreto Fed. n\u00ba 81.033 de 15\/12\/77&nbsp; &#8211; Publica\u00e7\u00e3o: 16\/12\/1977<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; <strong>1\u00aa Renova\u00e7\u00e3o:<\/strong> Decreto Estadual n\u00ba 6482 de 15\/03\/2010 &#8211; Validade:14\/03\/2015<br>&#8211; <strong>2\u00aa Renova\u00e7\u00e3o:<\/strong> Decreto Estadual n\u00ba 1696 de 18\/06\/2015 &#8211; Validade: 14\/03\/2019<br>&#8211; <strong>3\u00aa Renova\u00e7\u00e3o:<\/strong> Decreto Estadual n\u00ba 0677 de 27\/02\/2019 &#8211; Validade: 14\/03\/2023<br>&#8211; <strong>4\u00aa Renova\u00e7\u00e3o:<\/strong> Portaria Estadual n\u00ba 139 de 24\/10\/2022 &#8211; Validade: 14\/03\/2027<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-cinza-color has-css-opacity has-cinza-background-color has-background is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veja tamb\u00e9m:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sites.uel.br\/prograd\/graduacao\/catalogo-dos-cursos-de-graduacao-indice\/\">Cat\u00e1logo dos Curso de Gradua\u00e7\u00e3o (Organiza\u00e7\u00e3o Curricular, Ementas, Corpo Docente<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sites.uel.br\/prograd\/graduacao\/projetos-pedagogicos\/\">Projetos Pedag\u00f3gicos dos Cursos de Gradua\u00e7\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00edmica &#8211; Bacharelado Reconhecimento: Decreto Fed. n\u00ba 81.033 de 15\/12\/77&nbsp; &#8211; Publica\u00e7\u00e3o: 16\/12\/1977 &#8211; 1\u00aa Renova\u00e7\u00e3o: Decreto Estadual n\u00ba 6482 de 15\/03\/2010 &#8211; Validade:14\/03\/2015&#8211; 2\u00aa Renova\u00e7\u00e3o: Decreto Estadual n\u00ba 1696 de 18\/06\/2015 &#8211; Validade: 14\/03\/2019&#8211; 3\u00aa Renova\u00e7\u00e3o: Decreto Estadual n\u00ba 0677 de 27\/02\/2019 &#8211; Validade: 14\/03\/2023&#8211; 4\u00aa Renova\u00e7\u00e3o: Portaria Estadual n\u00ba 139 de 24\/10\/2022 &#8211; [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-35068","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/pages\/35068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/comments?post=35068"}],"version-history":[{"count":5,"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/pages\/35068\/revisions"}],"predecessor-version":[{"id":35253,"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/pages\/35068\/revisions\/35253"}],"wp:attachment":[{"href":"https:\/\/sites.uel.br\/prograd\/wp-json\/wp\/v2\/media?parent=35068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}